{"id":14009,"date":"2023-10-26T12:33:44","date_gmt":"2023-10-26T10:33:44","guid":{"rendered":"https:\/\/soccerbettingtipsandpredictions.com\/?p=14009"},"modified":"2023-10-26T12:33:44","modified_gmt":"2023-10-26T10:33:44","slug":"soccer-10-results-payouts-wed-25-oct","status":"publish","type":"post","link":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/2023\/10\/26\/soccer-10-results-payouts-wed-25-oct\/","title":{"rendered":"Soccer 10 Results &#038; Payouts Wed 25 Oct"},"content":{"rendered":"<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\"><strong>Soccer 10 Results &amp; Payouts<\/strong><\/div>\n<div>Wed 25 Oct<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div>\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div><strong>Everyone Loves a WINNER!<\/strong><\/div>\n<\/div>\n<p>Check out our free 1&#215;2 &amp; O\/U soccer tips for these (10) Games<\/p>\n<\/div>\n<\/div>\n<div>\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<p><strong>Good Luck #Mapunters<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<p><a href=\"https:\/\/www.betway.co.za\/offers\/huawei-giveaway\/?btag=P57206-PR22387-CM57443-TS1970593&amp;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-7029\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2022\/10\/BW_SA_728_90_LuckyDraw_HuaweiGiveawy.gif\" alt=\"\" width=\"728\" height=\"90\" \/><\/a><\/p>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">Soccer 10 Results &amp; Payouts<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div>\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div><\/div>\n<div>\n<div class=\"panel poolinformation\">\n<div>\n<div class=\"pooldateindicator4R\">Wed 25 Oct\u00a0&#8211; S10\u00a0V3<\/div>\n<table class=\"pooltable\">\n<tbody>\n<tr>\n<th>Match<\/th>\n<th>Team A<\/th>\n<th>Score<\/th>\n<th>Team B<\/th>\n<\/tr>\n<tr>\n<td class=\"bold\">M1<\/td>\n<td>Birmingham City<\/td>\n<td>0 &#8211; 2<\/td>\n<td class=\"righttext\">Hull City<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M2<\/td>\n<td>Bristol City<\/td>\n<td>0 &#8211; 1<\/td>\n<td class=\"righttext\">Ipswich Town<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M3<\/td>\n<td>Plymouth Argyle<\/td>\n<td>3 &#8211; 0<\/td>\n<td class=\"righttext\">Sheffield Wednesday<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M4<\/td>\n<td>Preston North End<\/td>\n<td>2 &#8211; 2<\/td>\n<td class=\"righttext\">Southampton<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M5<\/td>\n<td>Rotherham United<\/td>\n<td>2 &#8211; 0<\/td>\n<td class=\"righttext\">Coventry City<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M6<\/td>\n<td>Stoke City<\/td>\n<td>1 &#8211; 0<\/td>\n<td class=\"righttext\">Leeds United<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M7<\/td>\n<td>RB Bragantino<\/td>\n<td>1 &#8211; 2<\/td>\n<td class=\"righttext\">Atletico Mineiro<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M8<\/td>\n<td>Palmeiras<\/td>\n<td>5 &#8211; 0<\/td>\n<td class=\"righttext\">Sao Paulo<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M9<\/td>\n<td>Cruzeiro<\/td>\n<td>3 &#8211; 0<\/td>\n<td class=\"righttext\">Bahia<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M10<\/td>\n<td>Gremio<\/td>\n<td>3 &#8211; 2<\/td>\n<td class=\"righttext\">Flamengo RJ<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"panel poolinformation\">Winning Combination:\u00a03\/3\/1\/2\/1\/1\/3\/1\/1\/1<br \/>\nStatus: Official<\/p>\n<div>Results: (9\/10)<br \/>\nNet 9\/10: R149,793.20<br \/>\nWinners:\u00a0104<br \/>\nDividend: R1,440.20<\/p>\n<\/div>\n<p>Results: (10\/10)<br \/>\nNet 10\/10: R599,173.23<br \/>\nWinners:\u00a04<br \/>\nDividend: R149,793.20<\/p>\n<\/div>\n<\/div>\n<div>\n<div class=\"pooldateindicator4R\">Wed 25 Oct\u00a0&#8211; S10\u00a0V2<\/div>\n<table class=\"pooltable\">\n<tbody>\n<tr>\n<th>Match<\/th>\n<th>Team A<\/th>\n<th>Score<\/th>\n<th>Team B<\/th>\n<\/tr>\n<tr>\n<td class=\"bold\">M1<\/td>\n<td>Feyenoord<\/td>\n<td>3 &#8211; 1<\/td>\n<td class=\"righttext\">Lazio<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M2<\/td>\n<td>Barcelona<\/td>\n<td>2 &#8211; 1<\/td>\n<td class=\"righttext\">Shakhtar Donetsk<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M3<\/td>\n<td>Celtic FC<\/td>\n<td>2 &#8211; 2<\/td>\n<td class=\"righttext\">Atletico Madrid<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M4<\/td>\n<td>Paris Saint-Germain<\/td>\n<td>3 &#8211; 0<\/td>\n<td class=\"righttext\">AC Milan<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M5<\/td>\n<td>Newcastle United<\/td>\n<td>0 &#8211; 1<\/td>\n<td class=\"righttext\">Borussia Dortmund<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M6<\/td>\n<td>RB Leipzig<\/td>\n<td>3 &#8211; 1<\/td>\n<td class=\"righttext\">Red Star Belgrade<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M7<\/td>\n<td>Young Boys<\/td>\n<td>1 &#8211; 3<\/td>\n<td class=\"righttext\">Manchester City<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M8<\/td>\n<td>Antwerp<\/td>\n<td>1 &#8211; 4<\/td>\n<td class=\"righttext\">FC Porto<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M9<\/td>\n<td>Gremio<\/td>\n<td>3 &#8211; 2<\/td>\n<td class=\"righttext\">Flamengo RJ<\/td>\n<\/tr>\n<tr>\n<td class=\"bold\">M10<\/td>\n<td>Cuiaba<\/td>\n<td>0 &#8211; 1<\/td>\n<td class=\"righttext\">Corinthians<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"panel poolinformation\">Winning Combination:\u00a01\/1\/2\/1\/3\/1\/3\/3\/1\/3<br \/>\nStatus: Official<\/p>\n<div>Results: (9\/10)<br \/>\nNet 9\/10: R323,523.53<br \/>\nWinners:\u00a04691<br \/>\nDividend: R68.80<\/p>\n<\/div>\n<p>Results: (10\/10)<br \/>\nNet 10\/10: R1,294,094.16<br \/>\nWinners:\u00a0260<br \/>\nDividend: R4,977.20<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>++<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div>\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\" style=\"text-align: center;\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"panel poolinformation\">\n<div class=\"panel poolinformation\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div class=\"pooldateindicator4R\">\n<div>Register NOW Choose your teams &amp; Start Winning*<\/div>\n<div><a href=\"https:\/\/www.betway.co.za\/offers\/huawei-giveaway\/?btag=P57206-PR22387-CM57443-TS1970593&amp;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-7029\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2022\/10\/BW_SA_728_90_LuckyDraw_HuaweiGiveawy.gif\" alt=\"\" width=\"728\" height=\"90\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"pooldateindicator4R\">\n<p><strong>Betting Tips Guide:<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p style=\"text-align: center;\"><strong>We use the common 1X2 three-way bet type, with the draw option.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Straight Selections are:<\/strong><\/p>\n<p style=\"text-align: center;\">1- Home Team to Win<br \/>\nX- Match to be a Draw<br \/>\n2- Away Team to Win<\/p>\n<p style=\"text-align: center;\"><strong>Doubles\/Triple Chance Selections cost extra<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Triple Bets are only available on soccer pools* type games<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Double Chance Betting<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Double chance covers <strong>two<\/strong> out of <strong>three<\/strong> (1X2) outcomes.<\/p>\n<p style=\"text-align: center;\">&#8216;1X&#8217; &#8211; stands for Home\/Draw<br \/>\n&#8216;X2&#8242; &#8211; stands for Draw\/Away<br \/>\n&#8217;12&#8217; &#8211; stands for Home\/Away<\/p>\n<p style=\"text-align: center;\"><em><strong>Triple Chance Betting<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Covers all three (1&#215;2) outcomes and <strong>closes<\/strong> the bet leg.<\/p>\n<p style=\"text-align: center;\">(1X2) \u2013 Home Win +Draw + Away Win<\/p>\n<p style=\"text-align: center;\"><em><strong>Banker Tips &amp; Code<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Soccer Banker Tips <strong>statistically<\/strong> speaking<\/p>\n<p style=\"text-align: center;\">have the best chance of winning<\/p>\n<p style=\"text-align: center;\">Combine several bet legs to make an (Accumulator)<\/p>\n<p style=\"text-align: center;\">Higher Odds = Bigger Payouts<\/p>\n<p style=\"text-align: center;\">More legs = More risk!<\/p>\n<p style=\"text-align: center;\">Tips, Odds &amp; Stats don&#8217;t play soccer!<\/p>\n<p style=\"text-align: center;\"><em><strong>Over\/Under (O\/U) Goals <\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Betting Explained:<\/strong><\/em><\/p>\n<p style=\"text-align: center;\">Bet on the <em><strong>TOTAL<\/strong><\/em> number of match goals<\/p>\n<p style=\"text-align: center;\">by either team after 90 mins<\/p>\n<p style=\"text-align: center;\"><strong>OVER GOALS BET MARKETS<\/strong><\/p>\n<p style=\"text-align: center;\">&#8211; O\/0.5 = 1+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/1.5 = 2+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/2.5 = 3+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/3.5 = 4+ goals<\/p>\n<p style=\"text-align: center;\">&#8211; O\/4.5 = 5+ goals<\/p>\n<p style=\"text-align: center;\"><strong>UNDER GOALS BET MARKETS<\/strong><\/p>\n<p style=\"text-align: center;\">&#8211; Under 0.5 = No goals (0-0)<\/p>\n<p style=\"text-align: center;\">&#8211; U\/1.5 = 1 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/2.5 = 2 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/3.5 = 3 or less goals<\/p>\n<p style=\"text-align: center;\">&#8211; U\/4.5 = 4 or less goals<\/p>\n<p style=\"text-align: center;\"><strong>BOTH TEAMS TO SCORE (BTTS) <\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>Betting Explained:<\/em><\/strong><\/p>\n<p style=\"text-align: center;\">BTTS is a popular betting market as it&#8217;s very easy to play<\/p>\n<p style=\"text-align: center;\">You bet either<strong> BTTS (Yes)<\/strong> or <strong>BTTS (No)<\/strong><\/p>\n<p style=\"text-align: center;\">Bet (<strong>Btts Yes<\/strong>) = Both teams need to score<\/p>\n<p style=\"text-align: center;\">Bet (<strong>Btts No<\/strong>) = one or both teams don&#8217;t score<\/p>\n<p style=\"text-align: center;\"><strong>Disclaimer:<\/strong><\/p>\n<p style=\"text-align: center;\">Anything can and does happen in sport, there are<strong> No Sure Bets<\/strong><\/p>\n<p style=\"text-align: center;\">Stats and data will help you win more often, the rest is up to Lady Luck!<\/p>\n<p style=\"text-align: center;\">This Web site does not offer (Bets) or (Lay Bets)<\/p>\n<p style=\"text-align: center;\">For (Entertainment Purposes Only) &#8211; Play At Your Own Risk*<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; line-height: 1.5;\">This Web site cannot be held responsible <\/span><span style=\"font-size: 16px; line-height: 1.5;\">for any <\/span><span style=\"font-size: 16px; line-height: 1.5;\">damages or losses <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 16px; line-height: 1.5;\">that could arise <\/span><span style=\"font-size: 16px; line-height: 1.5;\">from\u00a0<\/span><span style=\"font-size: 16px; line-height: 1.5;\">acting upon the information contained herein<\/span><\/p>\n<p style=\"text-align: center;\"><strong>Data changes constantly &#8211; All information is (subject to change)<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Always Double Check latest bet data before placing your bet*<\/strong><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\">Play Responsibly &#8211; Never Play With Money You Can&#8217;t Afford To Lose!!!<\/p>\n<p style=\"text-align: center;\"><em>The South African Responsible Gambling Foundation (SARGF) <\/em><\/p>\n<p style=\"text-align: center;\"><em>provides Free Help &#8230; 006 008 Or SMS HELP To 076 675 0710 <\/em><\/p>\n<p style=\"text-align: center;\"><em>helpline@responsiblegambling.org.za<\/em><\/p>\n<\/div>\n<div>\n<p style=\"text-align: center;\"><em>This web site is for entertainment purposes (Only) <\/em><\/p>\n<p style=\"text-align: center;\"><em>AND HAS NO AFFILIATION TO TAB or National Lottery<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>Errors and omissions excepted (E&amp;OE) &#8211; Use this site as a guide at your own risk.<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.betway.co.za\/offers\/huawei-giveaway\/?btag=P57206-PR22387-CM57443-TS1970593&amp;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-7029\" src=\"https:\/\/diskitips1x2.co.za\/wp-content\/uploads\/2022\/10\/BW_SA_728_90_LuckyDraw_HuaweiGiveawy.gif\" alt=\"\" width=\"728\" height=\"90\" \/><\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Soccer 10 Results &amp; Payouts Wed 25 Oct Everyone Loves a WINNER! Check out our free 1&#215;2 &amp; O\/U soccer tips for these (10) Games <a class=\"mh-excerpt-more\" href=\"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/2023\/10\/26\/soccer-10-results-payouts-wed-25-oct\/\" title=\"Soccer 10 Results &#038; Payouts Wed 25 Oct\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false},"categories":[8,289],"tags":[62],"_links":{"self":[{"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/posts\/14009"}],"collection":[{"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/comments?post=14009"}],"version-history":[{"count":1,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/posts\/14009\/revisions"}],"predecessor-version":[{"id":14010,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/posts\/14009\/revisions\/14010"}],"wp:attachment":[{"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/media?parent=14009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/categories?post=14009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soccerbettingtipsandpredictions.com\/index.php\/wp-json\/wp\/v2\/tags?post=14009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}